{"id":120700,"date":"2024-08-02T19:55:33","date_gmt":"2024-08-02T17:55:33","guid":{"rendered":"https:\/\/golfbelgium.be\/?p=120700"},"modified":"2024-08-13T09:45:26","modified_gmt":"2024-08-13T07:45:26","slug":"resultats-des-championnats-nationaux-young-adults-mid-am","status":"publish","type":"post","link":"https:\/\/golfbelgium.be\/fr\/resultats-des-championnats-nationaux-young-adults-mid-am\/","title":{"rendered":"R\u00e9sultats des Championnats Nationaux Young Adults &#038; Mid-Am"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.9.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-36px|auto||auto||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-120706 alignnone size-medium\" src=\"https:\/\/golfbelgium.be\/wp-content\/uploads\/2024\/08\/img-20240730-wa0025-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-120704 alignnone size-medium\" src=\"https:\/\/golfbelgium.be\/wp-content\/uploads\/2024\/08\/img-20240730-wa0023-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.9.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-120710 alignnone size-medium\" src=\"https:\/\/golfbelgium.be\/wp-content\/uploads\/2024\/08\/img-20240730-wa0020-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-120708 alignnone size-medium\" src=\"https:\/\/golfbelgium.be\/wp-content\/uploads\/2024\/08\/img-20240730-wa0011-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.9.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>&nbsp;<\/p>\n<p>Les Championnats Nationaux Young Adults et Mid-Am se sont d\u00e9roul\u00e9s les 27 et 28 juillet au Royal Latem Golf Club.<\/p>\n<p>Ces championnats se jouaient en 2 tours Stroke Play.<\/p>\n<div>Une centaine de participants, hommes et dames confondus, ont pris le d\u00e9part avec une participation importante dans la cat\u00e9gorie Mid-Am.<\/div>\n<div>\u00a0<\/div>\n<div>Chez les Young Adults, c&rsquo;est le Golf de Rigen\u00e9e qui a vu la victoire de deux de ses repr\u00e9sentants : chez les messieurs, Louis Defleur (72-73) et Sarah Helm (81-79) chez les dames. Finn Smolders (74-76) du Golf de Kampenhout et Sarah Degreef (80-90) du Golf Club 7 Fontaines ont termin\u00e9 Runner-Up.<\/div>\n<div>\u00a0<\/div>\n<div>C\u00f4t\u00e9 Mid-Am, tant du c\u00f4t\u00e9 masculin que f\u00e9minin, la lutte pour le titre a \u00e9t\u00e9 tr\u00e8s serr\u00e9e!<\/div>\n<div>Chez les messieurs, Cl\u00e9ment Notermans du Golf de Li\u00e8ge Gomz\u00e9 a termin\u00e9 champion avec les scores de 73 et 72 devan\u00e7ant d&rsquo;un seul coup Andreas Reygaert (75-71) du Golf Ch\u00e2teau de La Tournette.<\/div>\n<div>Chez les dames, 2 joueuses ont termin\u00e9 ex-aequo \u00e0 l&rsquo;issue des 2 tours Stroke Play (+9). Apr\u00e8s le deuxi\u00e8me trou de play-off, la victoire est revenue \u00e0 Tamara Luccioli (76-77) du Royal Golf de Sart Tilman devant Mathilde Bertuol (77-76) du Golf Club 7 Fontaines.<\/div>\n<div>\u00a0<\/div>\n<div>Toutes nos f\u00e9licitations aux heureux gagnants et \u00e0 leurs runner-up pour ces r\u00e9sultats dans ces 2 championnats!<\/div>\n<div class=\"yj6qo ajU\">\u00a0<\/div>\n<div><em>Royal Latem Golf Club: un des parcours les plus anciens (1909) de Belgique, pr\u00e9c\u00e9demment appel\u00e9 \u00ab\u00a0les Buttes Blanches\u00a0\u00bb d&rsquo;apr\u00e8s les gen\u00eats poussant sur ses anciennes buttes. Il est renomm\u00e9 pour son\u00a0parcours bois\u00e9, assez technique et \u00e9troit, comprenant quelques pi\u00e8ces d&rsquo;eau et de nombreux bunkers.<\/em><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Les Championnats Nationaux Young Adults et Mid-Am se sont d\u00e9roul\u00e9s les 27 et 28 juillet au Royal Latem Golf Club. Ces championnats se jouaient en 2 tours Stroke Play. Une centaine de participants, hommes et dames confondus, ont pris le d\u00e9part avec une participation importante dans la cat\u00e9gorie Mid-Am. \u00a0 Chez les Young Adults, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":120717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"R\u00e9sultats des Championnats Nationaux Young Adults &amp; Mid-Am 2024","_seopress_titles_desc":"Les Championnats Nationaux Young Adults et Mid-Am se sont d\u00e9roul\u00e9s les 27 et 28 juillet au Royal Latem Golf Club.","_seopress_robots_index":"","_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[209,1,208],"tags":[],"class_list":["post-120700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-midam-tour","category-rbgf","category-young-adults-tour"],"acf":[],"_links":{"self":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/posts\/120700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/comments?post=120700"}],"version-history":[{"count":5,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/posts\/120700\/revisions"}],"predecessor-version":[{"id":120725,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/posts\/120700\/revisions\/120725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/media\/120717"}],"wp:attachment":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/media?parent=120700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/categories?post=120700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/tags?post=120700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}