{"id":32079,"date":"2020-02-24T09:29:51","date_gmt":"2020-02-24T08:29:51","guid":{"rendered":"https:\/\/dev.notredemo.be\/golf\/?p=32079"},"modified":"2020-07-16T11:11:23","modified_gmt":"2020-07-16T09:11:23","slug":"giovanni-tadiotto-sur-le-podium-aux-usa","status":"publish","type":"post","link":"https:\/\/golfbelgium.be\/fr\/giovanni-tadiotto-sur-le-podium-aux-usa\/","title":{"rendered":"Giovanni Tadiotto sur le podium aux USA"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.0.11&Prime;][et_pb_row _builder_version=\u00a0\u00bb4.0.11&Prime;][et_pb_column _builder_version=\u00a0\u00bb4.0.11&Prime; type=\u00a0\u00bb4_4&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.0.11&Prime; hover_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Petit regard sur nos Belges \u00e0 l&rsquo;\u00e9tranger&#8230; L&rsquo;universit\u00e9 de l&rsquo;Illinois, avec Giovanni Tadiotto et Adrien Dumont de Chassart, a termin\u00e9 \u00e0 la 4e place du classement par \u00e9quipe ce week-end lors du John Burns Intercollegiate.<\/p>\n<p>Giovanni Tadiotto a, quant \u00e0 lui, pris la 3e place au classement individuel! Une magnifique performance apr\u00e8s sa 4 place au Mobile Sports Authority Intercollegiate, la semaine pr\u00e9c\u00e9dente. Adrien Dumont de Chassart a termin\u00e9 67e.<\/p>\n<p>D\u00e9couvrez les r\u00e9sultats du <a href=\"http:\/\/results.golfstat.com\/public\/leaderboards\/gsnav.cfm?pg=player&amp;tid=18319&amp;fbclid=IwAR0NcMOW_6wyjwxC5lbx2w5gGPQMgEuAZFsZUqQY3Mz-5O_IgjTnHfnNCio\" target=\"_blank\" rel=\"noopener noreferrer\">John Burns Intercollegiate<\/a>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petit regard sur nos Belges \u00e0 l&rsquo;\u00e9tranger&#8230; L&rsquo;universit\u00e9 de l&rsquo;Illinois, avec Giovanni Tadiotto et Adrien Dumont de Chassart, a termin\u00e9 \u00e0 la 4e place du classement par \u00e9quipe ce week-end lors du John Burns Intercollegiate. Giovanni Tadiotto a, quant \u00e0 lui, pris la 3e place au classement individuel! Une magnifique performance apr\u00e8s sa 4 place [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[261,58],"class_list":["post-32079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rbgf","tag-abroad","tag-amateurs"],"acf":[],"_links":{"self":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/posts\/32079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/comments?post=32079"}],"version-history":[{"count":0,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/posts\/32079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/media\/32086"}],"wp:attachment":[{"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/media?parent=32079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/categories?post=32079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfbelgium.be\/fr\/wp-json\/wp\/v2\/tags?post=32079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}